{"id":138,"count":11,"description":"","link":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/","name":"Saatgut","slug":"saatgut","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saatgut Archivi - Comagricola Green Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saatgut Archivi - Comagricola Green Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/\" \/>\n<meta property=\"og:site_name\" content=\"Comagricola Green Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/\",\"url\":\"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/\",\"name\":\"Saatgut Archivi - Comagricola Green Europe\",\"isPartOf\":{\"@id\":\"https:\/\/www.comagricola.com\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.comagricola.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saatgut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comagricola.com\/de\/#website\",\"url\":\"https:\/\/www.comagricola.com\/de\/\",\"name\":\"Green Europe Comagricola\",\"description\":\"Semi e Fertilizzanti\",\"publisher\":{\"@id\":\"https:\/\/www.comagricola.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comagricola.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comagricola.com\/de\/#organization\",\"name\":\"COMAGRICOLA GREEN EUROPE SRL\",\"url\":\"https:\/\/www.comagricola.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.comagricola.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comagricola.com\/wp-content\/uploads\/2020\/12\/logo-comagricola.svg\",\"contentUrl\":\"https:\/\/www.comagricola.com\/wp-content\/uploads\/2020\/12\/logo-comagricola.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"COMAGRICOLA GREEN EUROPE SRL\"},\"image\":{\"@id\":\"https:\/\/www.comagricola.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/it-it.facebook.com\/pages\/category\/Company\/Comagricola-Green-Europe-srl-1189465271123595\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saatgut Archivi - Comagricola Green Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/","og_locale":"de_DE","og_type":"article","og_title":"Saatgut Archivi - Comagricola Green Europe","og_url":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/","og_site_name":"Comagricola Green Europe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/","url":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/","name":"Saatgut Archivi - Comagricola Green Europe","isPartOf":{"@id":"https:\/\/www.comagricola.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.comagricola.com\/de\/categoria-prodotto\/saatgut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.comagricola.com\/de\/"},{"@type":"ListItem","position":2,"name":"Saatgut"}]},{"@type":"WebSite","@id":"https:\/\/www.comagricola.com\/de\/#website","url":"https:\/\/www.comagricola.com\/de\/","name":"Green Europe Comagricola","description":"Semi e Fertilizzanti","publisher":{"@id":"https:\/\/www.comagricola.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comagricola.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.comagricola.com\/de\/#organization","name":"COMAGRICOLA GREEN EUROPE SRL","url":"https:\/\/www.comagricola.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.comagricola.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.comagricola.com\/wp-content\/uploads\/2020\/12\/logo-comagricola.svg","contentUrl":"https:\/\/www.comagricola.com\/wp-content\/uploads\/2020\/12\/logo-comagricola.svg","width":"1024","height":"1024","caption":"COMAGRICOLA GREEN EUROPE SRL"},"image":{"@id":"https:\/\/www.comagricola.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it-it.facebook.com\/pages\/category\/Company\/Comagricola-Green-Europe-srl-1189465271123595\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.comagricola.com\/de\/wp-json\/wp\/v2\/product_cat\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comagricola.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.comagricola.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.comagricola.com\/de\/wp-json\/wp\/v2\/product?product_cat=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}